{"id":16125,"date":"2017-05-18T16:47:10","date_gmt":"2017-05-18T14:47:10","guid":{"rendered":"http:\/\/localhost\/larouelibreNew\/?page_id=16125"},"modified":"2022-05-04T16:48:14","modified_gmt":"2022-05-04T14:48:14","slug":"subventions-credits-impot","status":"publish","type":"page","link":"https:\/\/www.larouelibre.fr\/blog\/velo-electrique\/subventions-credits-impot\/","title":{"rendered":"Subventions | Cr\u00e9dits Imp\u00f4t"},"content":{"rendered":"\n<h2 class=\"has-text-align-center wp-block-heading\">SUBVENTIONS: AIDE DE L&rsquo;ETAT<\/h2>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n<p style=\"text-align: justify;\"><strong>La subvention VAE:<\/strong>\u00a0Il s&rsquo;agit d&rsquo;une aide financi\u00e8re propos\u00e9e par l&rsquo;Etat fran\u00e7ais lors de l&rsquo;achat d&rsquo;un V\u00e9lo \u00e0 assistance \u00e9lectrique pouvant absorber jusqu&rsquo;\u00e0 33% du prix d&rsquo;acquisition du VAE. Cette subvention fait partie de la loi relative \u00e0 la\u00a0<a href=\"https:\/\/www.ecologique-solidaire.gouv.fr\/loi-transition-energetique-croissance-verte\">transition \u00e9cologique<\/a>, l&rsquo;Etat encourageant\u00a0tous les Fran\u00e7ais \u00e0 modifier leurs habitudes de vie de fa\u00e7on \u00e9cologique et responsable en ciblant particuli\u00e8rement\u00a0les\u00a0<a href=\"https:\/\/www.fournisseur-energie.com\/velos\/\">transports<\/a> et l&rsquo;habitat. Cette subvention est soumise \u00e0 certaines conditions que vous pouvez consulter\u00a0<a href=\"https:\/\/www.fournisseur-energie.com\/actualites\/aide-financiere-vae\/\">ici<\/a>. Elle est cumulable avec les aides dispens\u00e9es par les collectivit\u00e9s locales: vous pouvez formuler votre demande de subvention sur le site du\u00a0<a href=\"https:\/\/www.service-public.fr\/particuliers\/vosdroits\/R47063\">service public<\/a>.\u00a0<\/p>\n<p style=\"text-align: justify;\">Vous pouvez aussi trouver un article exhaustif sur le v\u00e9lo \u00e0 assistance \u00e9lectrique et davantage d&rsquo;informations vis-\u00e0-vis des subventions et de leurs \u00e9ligibilit\u00e9s ci-apr\u00e8s\u00a0<a href=\"https:\/\/www.fournisseur-energie.com\/actualites\/aide-financiere-vae\/\">https:\/\/www.fournisseur-energie.com\/actualites\/aide-financiere-vae\/<\/a>.\u00a0\u00a0<\/p>\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"titreChapitre_-89621379310948126\">Le bonus v\u00e9lo \u00e9tendu aux v\u00e9los cargo<\/h2>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Le bonus v\u00e9lo jusque-l\u00e0 r\u00e9serv\u00e9 aux v\u00e9los \u00e0 assistance \u00e9lectrique concerne d\u00e9sormais&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>les v\u00e9los&nbsp;\u00ab&nbsp;<em>cargo<\/em>&nbsp;\u00bb, \u00e9lectriques ou non. Il s\u2019agit des v\u00e9los am\u00e9nag\u00e9s pour permettre le transport de personnes ou de marchandises \u00e0 l\u2019arri\u00e8re ou l\u2019avant du conducteur ou pour r\u00e9pondre aux besoins de personnes en situation de handicap&nbsp;;<\/li><li>les remorques \u00e9lectriques pour cycles.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Pour en b\u00e9n\u00e9ficier, vous devez remplir les 4 conditions suivantes :<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00eatre majeur<\/li><li>justifier d\u2019un domicile en France<\/li><li>avoir un revenu fiscal de r\u00e9f\u00e9rence par part de l\u2019ann\u00e9e pr\u00e9c\u00e9dant l\u2019achat du v\u00e9lo inf\u00e9rieur ou \u00e9gal \u00e0&nbsp;13&nbsp;489&nbsp;\u20ac&nbsp;<\/li><li>achat entre le 26\/07\/21 et le 31\/12\/22<\/li><\/ul>\n\n\n\n<p>Vous ne devez pas vendre le v\u00e9lo cargo ou la remorque \u00e9lectrique dans l\u2019ann\u00e9e suivant son achat. Le montant du bonus est diff\u00e9rent de celui vers\u00e9 pour les v\u00e9los \u00e0 assistance \u00e9lectrique. Il est \u00e9gal \u00e0&nbsp;40&nbsp;%&nbsp;du prix d\u2019acquisition, dans la limite de&nbsp;1&nbsp;000&nbsp;\u20ac. Cette aide est valable aussi pour les entreprises \u00e9tablies en France.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Attention,<\/strong>&nbsp;<strong>l\u2019aide est vers\u00e9e au maximum une fois par personne jusqu\u2019au 31 d\u00e9cembre 2022.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\">Retrouvez les d\u00e9marches \u00e0 accomplir&nbsp;<a href=\"https:\/\/www.service-public.fr.preprod.ext.dila.fr\/particuliers\/vosdroits\/F35475\">dans cette fiche d\u2019information<\/a><\/p>\n\n\n\n<div style=\"height:63px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">SUBVENTIONS M\u00c9TROPOLE NICE COTE D&rsquo;AZUR<\/h2>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"has-text-align-center has-vivid-cyan-blue-color has-text-color wp-block-heading\">DEUX ROUES ELECTRIQUE<\/h2>\n\n\n\n<p> <\/p>\n\n\n\n<p class=\"has-text-align-justify\">La M\u00e9tropole encourage la mobilit\u00e9 \u00e9lectrique en instituant un dispositif de subventionnement pour les particuliers \u00e9tablis \u00e0 titre principal sur le territoire m\u00e9tropolitain afin de se doter d\u2019un deux roues \u00e9lectrique.&nbsp;<strong>Une aide de 25% du prix d\u2019achat en \u20ac ttc, plafonn\u00e9e \u00e0 400 \u20ac<\/strong>&nbsp;Vous contribuez ainsi \u00e0 la pr\u00e9servation de l\u2019environnement et de la sant\u00e9 publique en participant activement \u00e0 la r\u00e9duction des \u00e9missions de gaz \u00e0 effet de serre ainsi qu\u2019\u00e0 la limitation des nuisances sonores, souhait\u00e9 par la M\u00e9tropole Nice C\u00f4te d\u2019Azur.&nbsp;<strong>Attention, ne sont pas \u00e9ligibles les kits \u00e9lectriques, les trottinettes \u00e9lectriques et les gyropodes.La subvention m\u00e9tropolitaine n\u2019est pas cumulable avec celle octroy\u00e9e pour les v\u00e9los \u00e0 propulsion humaine.<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\">Plateforme de demande en ligne sur&nbsp;aidesecocovid19.nicecotedazur.org<\/h3>\n\n\n\n<p class=\"has-text-align-justify\">Pour v\u00e9rifier votre \u00e9ligibilit\u00e9, s\u2019inscrire et transmettre les documents demand\u00e9s \u00e0&nbsp;<a href=\"https:\/\/aidesecocovid19.nicecotedazur.org\/\">aidesecocovid19.nicecotedazur.org<\/a>&nbsp;Vous pouvez suivre l\u2019\u00e9volution de votre dossier directement sur la plateforme de d\u00e9pose du dossier \u00e0 l\u2019aide de votre identifiant et de votre mot de passe.<br>Tout le dossier doit \u00eatre aux m\u00eames nom et pr\u00e9nom que ceux mentionn\u00e9s sur la facture. Tout le dossier doit \u00eatre aux m\u00eames nom et pr\u00e9nom que ceux mentionn\u00e9s sur la facture. La falsification de documents est passible de poursuites.&nbsp;Le versement de la subvention peut prendre 6 mois.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Ne pas renvoyer les documents papier \u00e0 la M\u00e9tropole.<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><strong>Pour \u00eatre complet le dossier doit comprendre :&nbsp;<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Dans le cas o\u00f9 le b\u00e9n\u00e9ficiaire est majeur :<\/strong><\/li><\/ul>\n\n\n\n<ol class=\"wp-block-list\"><li>la convention originale sign\u00e9e portant la mention manuscrite \u00ab lu et approuv\u00e9 \u00bb, (document t\u00e9l\u00e9chargeable \u00e0 l\u2019\u00e9tape 4 de l\u2019inscription)<\/li><li>l\u2019attestation sur l\u2019honneur (original manuscrit), \u00e0 ne pas revendre le v\u00e9hicule \u00e9lectrique aid\u00e9 sous peine de restituer la subvention \u00e0 la M\u00e9tropole, \u00e0 apporter la preuve au service m\u00e9tropolitain, qui en fera la demande, qu\u2019il est bien en possession du v\u00e9hicule \u00e9lectrique aid\u00e9 (document t\u00e9l\u00e9chargeable \u00e0 l\u2019\u00e9tape 4 de l\u2019inscription)<\/li><li>la copie de la facture d\u2019achat acquitt\u00e9e du deux-roues \u00e9lectrique mentionnant le mod\u00e8le.<\/li><li>la copie du certificat d\u2019homologation du v\u00e9lo \u00e0 assistance \u00e9lectrique correspondant au mod\u00e8le not\u00e9 sur la facture ou de la carte grise du deux roues \u00e0 moteur \u00e9lectrique immatricul\u00e9,<\/li><li>le plus r\u00e9cent des documents suivants, \u00e0 savoir le dernier avis d\u2019imposition sur le revenu ou l\u2019avis de situation d\u00e9claratif ou la taxe d\u2019habitation, complet (deux volets \u2013 pas d\u2019\u00e9ch\u00e9ancier, pas de foncier), au m\u00eame nom, pr\u00e9nom et adresse que ceux figurant sur la facture du v\u00e9lo ou la carte grise du deux roues \u00e0 moteur \u00e9lectrique,&nbsp;<\/li><li>fournir une attestation d\u2019h\u00e9bergement (original manuscrit) si vivant chez une tierce personne justifiant le domicile du b\u00e9n\u00e9ficiaire mentionn\u00e9 sur les documents pr\u00e9c\u00e9dents. Dans le cas o\u00f9 il n\u2019est pas possible de fournir les documents pr\u00e9c\u00e9dents (6 et 7), aux m\u00eames nom, pr\u00e9nom et adresse, fournir un bail ou acte notari\u00e9 d\u2019achat,<\/li><li>le relev\u00e9 d\u2019identit\u00e9 bancaire.<\/li><\/ol>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Dans le cas o\u00f9 le b\u00e9n\u00e9ficiaire est mineur<\/strong><\/li><\/ul>\n\n\n\n<p>Les m\u00eames documents que ceux \u00e9nonc\u00e9s ci-dessus sont renseign\u00e9s au&nbsp;<strong>nom et pr\u00e9nom du mineur&nbsp;<\/strong>b\u00e9n\u00e9ficiaire.&nbsp;<strong>De plus, le repr\u00e9sentant l\u00e9gal doit :<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>compl\u00e9ter les encarts figurant sur la demande de formulaire, l\u2019attestation sur l\u2019honneur et la convention,<\/li><li>contresigner ces trois derniers documents,<\/li><li>fournir une attestation d\u2019h\u00e9bergement (original manuscrit) justifiant le domicile du b\u00e9n\u00e9ficiaire mineur mentionn\u00e9 sur les documents pr\u00e9c\u00e9dents,<\/li><li>fournir une attestation sur l\u2019honneur (original manuscrit) que la personne est bien le repr\u00e9sentant l\u00e9gal du mineur b\u00e9n\u00e9ficiaire.<\/li><\/ol>\n\n\n\n<p class=\"has-text-align-center\"><strong>Toutes les pi\u00e8ces justificatives doivent comporter une seule et m\u00eame adresse. L\u2019administration pourra demander toutes pi\u00e8ces compl\u00e9mentaires.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Contact :\u00a0<a href=\"mailto:aidesmobilite@nicecotedazur.org%20\">aidesmobilite@nicecotedazur.org<\/a><\/strong><\/p>\n\n\n\n<div style=\"height:41px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-text-align-center has-vivid-cyan-blue-color has-text-color wp-block-heading\">VELO A PROPULSION HUMAINE<\/h2>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n<div style=\"text-align: justify;\">La M\u00e9tropole encourage la mobilit\u00e9 durable en instituant un dispositif de subventionnement pour les particuliers \u00e9tablis \u00e0 titre principal sur le territoire m\u00e9tropolitain afin de se doter d\u2019un v\u00e9lo \u00e0 propulsion humaine.<\/div>\n<div>\u00a0<\/div>\n<div style=\"text-align: center;\"><strong>Une aide de 50% du prix d\u2019achat en \u20ac ttc, plafonn\u00e9e \u00e0 100 \u20ac, est accord\u00e9e.<\/strong><\/div>\n<div>\u00a0<\/div>\n<div style=\"text-align: justify;\">Vous contribuez ainsi \u00e0 la pr\u00e9servation de l\u2019environnement et de la sant\u00e9 publique en participant activement \u00e0 la r\u00e9duction des \u00e9missions de gaz \u00e0 effet de serre ainsi qu\u2019\u00e0 la limitation des nuisances sonores, souhait\u00e9 par la M\u00e9tropole Nice C\u00f4te d\u2019Azur.<\/div>\n<div>\u00a0<\/div>\n<div style=\"text-align: center;\"><strong>Attention, les v\u00e9los pour enfants ne sont pas \u00e9ligibles.<\/strong><\/div>\n<div style=\"text-align: center;\">\u00a0<\/div>\n<div style=\"text-align: center;\"><strong>La subvention m\u00e9tropolitaine n\u2019est pas cumulable avec celle octroy\u00e9e pour les deux roues \u00e9lectrique.<\/strong><\/div>\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Plateforme de demande en ligne sur aidesecocovid19.nicecotedazur.org<\/h3>\n\n\n\n<p class=\"has-text-align-justify\">Pour v\u00e9rifier votre \u00e9ligibilit\u00e9, s\u2019inscrire et transmettre les documents demand\u00e9s \u00e0&nbsp;<a href=\"https:\/\/aidesecocovid19.nicecotedazur.org\/\">aidesecocovid19.nicecotedazur.org<\/a>&nbsp;Vous pouvez suivre l\u2019\u00e9volution de votre dossier directement sur la plateforme de d\u00e9pose du dossier \u00e0 l\u2019aide de votre identifiant et de votre mot de passe. Tout le dossier doit \u00eatre aux m\u00eames nom et pr\u00e9nom que ceux mentionn\u00e9s sur la facture. La falsification de documents est passible de poursuites.&nbsp;&nbsp;Le versement de la subvention peut prendre 6 mois.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Ne pas renvoyer les documents papier \u00e0 la M\u00e9tropole.<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><strong>Pour \u00eatre complet le dossier doit comprendre :&nbsp;<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>la convention originale sign\u00e9e portant la mention manuscrite \u00ab lu et approuv\u00e9 \u00bb, (document t\u00e9l\u00e9chargeable \u00e0 l\u2019\u00e9tape 4 de l\u2019inscription)<\/li><li>l\u2019attestation sur l\u2019honneur (original manuscrit), engageant \u00e0 ne pas revendre le v\u00e9lo aid\u00e9 sous peine de restituer la subvention \u00e0 la M\u00e9tropole Nice C\u00f4te d\u2019Azur, \u00e0 apporter la preuve au service m\u00e9tropolitain, qui en fera la demande, qu\u2019il est bien en possession du v\u00e9lo aid\u00e9, (document t\u00e9l\u00e9chargeable \u00e0 l\u2019\u00e9tape 4 de l\u2019inscription)<\/li><li>la copie de la facture d\u2019achat acquitt\u00e9e du v\u00e9lo mentionnant le mod\u00e8le,<\/li><li>le dernier avis d\u2019imposition sur le revenu connu et complet,<\/li><li>l\u2019attestation d\u2019h\u00e9bergement (original manuscrit) si vivant chez une tierce personne justifiant le domicile du b\u00e9n\u00e9ficiaire mentionn\u00e9 sur les documents pr\u00e9c\u00e9dents,<\/li><li>la copie de la pi\u00e8ce d\u2019identit\u00e9 (recto-verso),<\/li><li>le relev\u00e9 d\u2019identit\u00e9 bancaire.<\/li><\/ol>\n\n\n\n<p class=\"has-text-align-center\"><strong>Toutes les pi\u00e8ces justificatives doivent comporter une seule et m\u00eame adresse. L\u2019administration pourra demander toutes pi\u00e8ces compl\u00e9mentaires.<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\">Contact :\u00a0<a href=\"mailto:aidesmobilite@nicecotedazur.org%20\">aidesmobilite@nicecotedazur.org<\/a><\/p>\n\n\n\n<div style=\"height:77px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">CR\u00c9DITS IMP\u00d4T ENTREPRISES<\/h2>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"has-text-align-justify\">Vous \u00eates g\u00e9rant d&rsquo;un soci\u00e9t\u00e9 et vous voulez aider vos salari\u00e9s&nbsp;\u00e0 se rendre sur leur lieu de travail en leur mettant \u00e0 disposition un v\u00e9lo, ou simplement vous d\u00e9placer \u00e0 v\u00e9lo lors de vos trajets quotidiens?<\/p>\n\n\n\n<p class=\"has-text-align-justify\">L&rsquo;Etat vous aide dans vos d\u00e9marches et vous permet de b\u00e9n\u00e9ficier d&rsquo;un r\u00e9duction d&rsquo;imp\u00f4t pour l&rsquo;achat de v\u00e9lo \u00ab\u00a0musculaire\u00a0\u00bb ou&nbsp;v\u00e9lo \u00e0 assistance \u00e9lectrique pour vous ou pour&nbsp;vos salari\u00e9s! Une tr\u00e8s bonne d\u00e9marche pour donner envie aux citoyens fran\u00e7ais de se mettre au v\u00e9lo et de changer leur mode de d\u00e9placement au quotidien. Vous voulez en savoir plus sur cette r\u00e9duction d&rsquo;imp\u00f4ts pour la mise \u00e0 disposition d&rsquo;un flotte de v\u00e9lo, t\u00e9l\u00e9charger le <a href=\"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2017\/08\/BOI-IS-RICI-20-30-20160706.pdf\">bulletin officiel des finances publiques ici<\/a>. Et bonne nouvelle, cette r\u00e9duction d&rsquo;imp\u00f4t est cumulable avec le <a href=\"http:\/\/www.larouelibre.fr\/velo-electrique\/subvention\/\">bonus de l&rsquo;Etat de 200\u20ac<\/a> pour l&rsquo;achat d&rsquo;un v\u00e9lo \u00e0 assistance \u00e9lectrique!<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Pour tous renseignements sur des v\u00e9los accessibles pour des d\u00e9placements inter-urbain rendez vous en magasin au <a href=\"http:\/\/www.larouelibre.fr\/contact\/giant-bike-shop\/\">20 Boulevard Arm\u00e9e des Alpes \u00e0 Nice <\/a>ou au <a href=\"http:\/\/www.larouelibre.fr\/contact\/la-roue-libre-cagnes-sur-mer\/\">15 avenue de Grasse \u00e0 Cagnes-sur-Mer<\/a>! Nos vendeurs passionn\u00e9s seront l\u00e0 pour vous aiguiller!<\/p>\n\n\n\n<p class=\"has-text-align-center\">D\u00e9couvrez tous nos v\u00e9los \u00e9lectrique dans <a href=\"http:\/\/www.larouelibre.fr\/nos-marques\/nos-gammes\/\">notre catalogue en ligne<\/a>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SUBVENTIONS: AIDE DE L&rsquo;ETAT La subvention VAE:\u00a0Il s&rsquo;agit d&rsquo;une aide financi\u00e8re propos\u00e9e par l&rsquo;Etat fran\u00e7ais lors de l&rsquo;achat d&rsquo;un V\u00e9lo \u00e0 assistance \u00e9lectrique pouvant absorber jusqu&rsquo;\u00e0 33% du prix d&rsquo;acquisition du VAE. Cette subvention fait partie de la loi relative \u00e0 la\u00a0transition \u00e9cologique, l&rsquo;Etat encourageant\u00a0tous les Fran\u00e7ais \u00e0 modifier leurs habitudes de vie de fa\u00e7on [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":15932,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false,"footnotes":""},"class_list":["post-16125","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Subventions | Cr\u00e9dits Imp\u00f4t - La Roue Libre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.larouelibre.fr\/blog\/velo-electrique\/subventions-credits-impot\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Subventions | Cr\u00e9dits Imp\u00f4t - La Roue Libre\" \/>\n<meta property=\"og:description\" content=\"SUBVENTIONS: AIDE DE L&rsquo;ETAT La subvention VAE:\u00a0Il s&rsquo;agit d&rsquo;une aide financi\u00e8re propos\u00e9e par l&rsquo;Etat fran\u00e7ais lors de l&rsquo;achat d&rsquo;un V\u00e9lo \u00e0 assistance \u00e9lectrique pouvant absorber jusqu&rsquo;\u00e0 33% du prix d&rsquo;acquisition du VAE. Cette subvention fait partie de la loi relative \u00e0 la\u00a0transition \u00e9cologique, l&rsquo;Etat encourageant\u00a0tous les Fran\u00e7ais \u00e0 modifier leurs habitudes de vie de fa\u00e7on [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.larouelibre.fr\/blog\/velo-electrique\/subventions-credits-impot\/\" \/>\n<meta property=\"og:site_name\" content=\"La Roue Libre\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-04T14:48:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.larouelibre.fr\/blog\/velo-electrique\/subventions-credits-impot\/\",\"url\":\"https:\/\/www.larouelibre.fr\/blog\/velo-electrique\/subventions-credits-impot\/\",\"name\":\"Subventions | Cr\u00e9dits Imp\u00f4t - La Roue Libre\",\"isPartOf\":{\"@id\":\"https:\/\/www.larouelibre.fr\/blog\/#website\"},\"datePublished\":\"2017-05-18T14:47:10+00:00\",\"dateModified\":\"2022-05-04T14:48:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.larouelibre.fr\/blog\/velo-electrique\/subventions-credits-impot\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.larouelibre.fr\/blog\/velo-electrique\/subventions-credits-impot\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.larouelibre.fr\/blog\/velo-electrique\/subventions-credits-impot\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.larouelibre.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Electrique\",\"item\":\"https:\/\/www.larouelibre.fr\/blog\/velo-electrique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Subventions | Cr\u00e9dits Imp\u00f4t\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.larouelibre.fr\/blog\/#website\",\"url\":\"https:\/\/www.larouelibre.fr\/blog\/\",\"name\":\"La Roue Libre\",\"description\":\"Votre sp\u00e9cialiste cycle, v\u00e9lo \u00e9lectrique, vtt, v\u00e9lo route \u00e0 Nice et cagnes sur mer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.larouelibre.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Subventions | Cr\u00e9dits Imp\u00f4t - La Roue Libre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.larouelibre.fr\/blog\/velo-electrique\/subventions-credits-impot\/","og_locale":"fr_FR","og_type":"article","og_title":"Subventions | Cr\u00e9dits Imp\u00f4t - La Roue Libre","og_description":"SUBVENTIONS: AIDE DE L&rsquo;ETAT La subvention VAE:\u00a0Il s&rsquo;agit d&rsquo;une aide financi\u00e8re propos\u00e9e par l&rsquo;Etat fran\u00e7ais lors de l&rsquo;achat d&rsquo;un V\u00e9lo \u00e0 assistance \u00e9lectrique pouvant absorber jusqu&rsquo;\u00e0 33% du prix d&rsquo;acquisition du VAE. Cette subvention fait partie de la loi relative \u00e0 la\u00a0transition \u00e9cologique, l&rsquo;Etat encourageant\u00a0tous les Fran\u00e7ais \u00e0 modifier leurs habitudes de vie de fa\u00e7on [&hellip;]","og_url":"https:\/\/www.larouelibre.fr\/blog\/velo-electrique\/subventions-credits-impot\/","og_site_name":"La Roue Libre","article_modified_time":"2022-05-04T14:48:14+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.larouelibre.fr\/blog\/velo-electrique\/subventions-credits-impot\/","url":"https:\/\/www.larouelibre.fr\/blog\/velo-electrique\/subventions-credits-impot\/","name":"Subventions | Cr\u00e9dits Imp\u00f4t - La Roue Libre","isPartOf":{"@id":"https:\/\/www.larouelibre.fr\/blog\/#website"},"datePublished":"2017-05-18T14:47:10+00:00","dateModified":"2022-05-04T14:48:14+00:00","breadcrumb":{"@id":"https:\/\/www.larouelibre.fr\/blog\/velo-electrique\/subventions-credits-impot\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.larouelibre.fr\/blog\/velo-electrique\/subventions-credits-impot\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.larouelibre.fr\/blog\/velo-electrique\/subventions-credits-impot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.larouelibre.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Electrique","item":"https:\/\/www.larouelibre.fr\/blog\/velo-electrique\/"},{"@type":"ListItem","position":3,"name":"Subventions | Cr\u00e9dits Imp\u00f4t"}]},{"@type":"WebSite","@id":"https:\/\/www.larouelibre.fr\/blog\/#website","url":"https:\/\/www.larouelibre.fr\/blog\/","name":"La Roue Libre","description":"Votre sp\u00e9cialiste cycle, v\u00e9lo \u00e9lectrique, vtt, v\u00e9lo route \u00e0 Nice et cagnes sur mer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.larouelibre.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/P7po7v-4c5","jetpack-related-posts":[{"id":15941,"url":"https:\/\/www.larouelibre.fr\/blog\/velo-electrique\/comprendre-le-vae\/","url_meta":{"origin":16125,"position":0},"title":"Comprendre le VAE","author":"La Roue Libre","date":"13 avril 2017","format":false,"excerpt":"Le VAE ou v\u00e9lo \u00e0 assistance \u00e9lectrique, est de plus en plus r\u00e9pandu de nos jours, mais comment marche t-il? Cette page vous permettra de mieux le comprendre et surtout de conna\u00eetre vos besoins et quel type de moteur ou batterie choisir pour votre futur achat! Le v\u00e9lo \u00e0 assistance\u2026","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":16129,"url":"https:\/\/www.larouelibre.fr\/blog\/contact\/nous-rejoindre\/","url_meta":{"origin":16125,"position":1},"title":"Nous Rejoindre","author":"La Roue Libre","date":"18 mai 2017","format":false,"excerpt":"LA ROUE LIBRE NICE 20 Boulevard Arm\u00e9e des Alpes 06300 NICE En Tramway Au D\u00e9part du Parcazur HENRI SAPPIA ou Parcazur PONT MICHEL \u2013 Possibilit\u00e9 de laisser son v\u00e9hicule gratuitement au parcasur HENRI SAPPIA ou PONT MICHEL pour tout achat d\u2019un pass Parcazur Aller\/Retour (tarif 3\u20ac) ou d\u2019une carte multi\u2026","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":18846,"url":"https:\/\/www.larouelibre.fr\/blog\/livraison\/","url_meta":{"origin":16125,"position":2},"title":"Livraison","author":"La Roue Libre","date":"30 mars 2018","format":false,"excerpt":"La Roue libre fait confiance \u00e0 La Poste pour la livraison de ses colis via Colissimo ou lettre suivie pour les petits objets (hors envoi de v\u00e9lo). Une fois le colis pr\u00e9par\u00e9 par nos soins, il vous sera livr\u00e9 dans un d\u00e9lai indicatif de 48h et remis dans votre bo\u00eete\u2026","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":16139,"url":"https:\/\/www.larouelibre.fr\/blog\/reprise\/","url_meta":{"origin":16125,"position":3},"title":"Reprise","author":"La Roue Libre","date":"18 mai 2017","format":false,"excerpt":"[ux_image id=\"12776\"] [gap height=\"60px\"] Vous voulez changer de v\u00e9lo et ne savez pas quoi faire de votre v\u00e9lo actuel? Il peut vous rapporter de l\u2019argent\u2026 Et oui votre r\u00e9seau de magasins La Roue Libre de Nice \u00e0 Cagnes-sur-mer rach\u00e8te votre v\u00e9lo \u00e0 sa valeur sur le march\u00e9 de l\u2019occasion! VTT,\u2026","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":23201,"url":"https:\/\/www.larouelibre.fr\/blog\/assurance-velo-garantie-vol\/","url_meta":{"origin":16125,"position":4},"title":"Assurance v\u00e9lo &#8211; Garantie vol","author":"La Roue Libre","date":"29 octobre 2024","format":false,"excerpt":"Bicytrust, la couverture vol et casse de votre v\u00e9lo adapt\u00e9e \u00e0 votre besoin. Pens\u00e9e pour et avec des cyclistes, l\u2019assurance vol et casse Bicytrust r\u00e9pond \u00e0 votre besoin de protection au quotidien. Vous aimez votre v\u00e9lo et vous l\u2019utilisez r\u00e9guli\u00e8rement pour un usage v\u00e9lotaf ou pour vos loisirs ? Vous\u2026","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2024\/06\/moustache2024-jeremie-reuiller-1931-750x500-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2024\/06\/moustache2024-jeremie-reuiller-1931-750x500-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2024\/06\/moustache2024-jeremie-reuiller-1931-750x500-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2024\/06\/moustache2024-jeremie-reuiller-1931-750x500-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":20279,"url":"https:\/\/www.larouelibre.fr\/blog\/atelier\/etude-posturale-bikefitting\/","url_meta":{"origin":16125,"position":5},"title":"Etude Posturale &#8211; Bikefitting","author":"La Roue Libre","date":"29 novembre 2018","format":false,"excerpt":"Pour chaque type d\u2019usage, une bonne position sur le v\u00e9lo est essentielle. C\u2019est la r\u00e9sultante d\u2019un parfait dosage entre puissance, efficacit\u00e9, r\u00e9sistance et confort. Une bonne position peut \u00e9viter les blessures et accro\u00eetre le confort tout en roulant en v\u00e9lo !\u00a0BikeFitting\u00a0a con\u00e7u un concept modulaire pour chaque type de cycliste,\u2026","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2018\/11\/image_bikefitting.jpg?fit=1092%2C815&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2018\/11\/image_bikefitting.jpg?fit=1092%2C815&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2018\/11\/image_bikefitting.jpg?fit=1092%2C815&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2018\/11\/image_bikefitting.jpg?fit=1092%2C815&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2018\/11\/image_bikefitting.jpg?fit=1092%2C815&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.larouelibre.fr\/blog\/wp-json\/wp\/v2\/pages\/16125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.larouelibre.fr\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.larouelibre.fr\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.larouelibre.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.larouelibre.fr\/blog\/wp-json\/wp\/v2\/comments?post=16125"}],"version-history":[{"count":57,"href":"https:\/\/www.larouelibre.fr\/blog\/wp-json\/wp\/v2\/pages\/16125\/revisions"}],"predecessor-version":[{"id":22526,"href":"https:\/\/www.larouelibre.fr\/blog\/wp-json\/wp\/v2\/pages\/16125\/revisions\/22526"}],"up":[{"embeddable":true,"href":"https:\/\/www.larouelibre.fr\/blog\/wp-json\/wp\/v2\/pages\/15932"}],"wp:attachment":[{"href":"https:\/\/www.larouelibre.fr\/blog\/wp-json\/wp\/v2\/media?parent=16125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}