{"id":20358,"date":"2019-01-04T12:01:30","date_gmt":"2019-01-04T11:01:30","guid":{"rendered":"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg"},"modified":"2019-01-04T12:01:30","modified_gmt":"2019-01-04T11:01:30","slug":"ovv-ami-carbon-newsletter-2","status":"inherit","type":"attachment","link":"https:\/\/www.larouelibre.fr\/blog\/ovv-ami-carbon-newsletter-2\/","title":{"rendered":"OVV-AMi-Carbon-Newsletter-2"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false},"class_list":["post-20358","attachment","type-attachment","status-inherit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>OVV-AMi-Carbon-Newsletter-2 - La Roue Libre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OVV-AMi-Carbon-Newsletter-2 - La Roue Libre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg\" \/>\n<meta property=\"og:site_name\" content=\"La Roue Libre\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg?fit=1400%2C934&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"934\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg\",\"url\":\"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg\",\"name\":\"OVV-AMi-Carbon-Newsletter-2 - La Roue Libre\",\"isPartOf\":{\"@id\":\"https:\/\/www.larouelibre.fr\/blog\/#website\"},\"datePublished\":\"2019-01-04T11:01:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.larouelibre.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OVV-AMi-Carbon-Newsletter-2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.larouelibre.fr\/blog\/#website\",\"url\":\"https:\/\/www.larouelibre.fr\/blog\/\",\"name\":\"La Roue Libre\",\"description\":\"Votre sp\u00e9cialiste cycle, v\u00e9lo \u00e9lectrique, vtt, v\u00e9lo route \u00e0 Nice et cagnes sur mer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.larouelibre.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OVV-AMi-Carbon-Newsletter-2 - La Roue Libre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg","og_locale":"fr_FR","og_type":"article","og_title":"OVV-AMi-Carbon-Newsletter-2 - La Roue Libre","og_url":"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg","og_site_name":"La Roue Libre","og_image":[{"width":1400,"height":934,"url":"https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg?fit=1400%2C934&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg","url":"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg","name":"OVV-AMi-Carbon-Newsletter-2 - La Roue Libre","isPartOf":{"@id":"https:\/\/www.larouelibre.fr\/blog\/#website"},"datePublished":"2019-01-04T11:01:30+00:00","breadcrumb":{"@id":"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.larouelibre.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"OVV-AMi-Carbon-Newsletter-2"}]},{"@type":"WebSite","@id":"https:\/\/www.larouelibre.fr\/blog\/#website","url":"https:\/\/www.larouelibre.fr\/blog\/","name":"La Roue Libre","description":"Votre sp\u00e9cialiste cycle, v\u00e9lo \u00e9lectrique, vtt, v\u00e9lo route \u00e0 Nice et cagnes sur mer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.larouelibre.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a7po7v-5im","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg?fit=600%2C400&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg?resize=600%2C400&amp;ssl=1 600w, https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg?resize=1199%2C800&amp;ssl=1 1199w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" data-attachment-id=\"20358\" data-permalink=\"https:\/\/www.larouelibre.fr\/blog\/ovv-ami-carbon-newsletter-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg?fit=1400%2C934&amp;ssl=1\" data-orig-size=\"1400,934\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"OVV-AMi-Carbon-Newsletter-2\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg?fit=600%2C400&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg?fit=696%2C464&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1400,"height":934,"file":"2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg","sizes":{"thumbnail":{"file":"OVV-AMi-Carbon-Newsletter-2-280x280.jpg","width":280,"height":280,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg?resize=280%2C280&ssl=1"},"medium":{"file":"OVV-AMi-Carbon-Newsletter-2-600x400.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg?fit=600%2C400&ssl=1"},"medium_large":{"file":"OVV-AMi-Carbon-Newsletter-2-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg?fit=696%2C464&ssl=1"},"large":{"file":"OVV-AMi-Carbon-Newsletter-2-1199x800.jpg","width":1199,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg?fit=696%2C464&ssl=1"},"woocommerce_thumbnail":{"file":"OVV-AMi-Carbon-Newsletter-2-300x300.jpg","width":300,"height":300,"uncropped":true,"mime_type":"image\/jpeg","source_url":"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2-300x300.jpg"},"woocommerce_single":{"file":"OVV-AMi-Carbon-Newsletter-2-600x400.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2-600x400.jpg"},"woocommerce_gallery_thumbnail":{"file":"OVV-AMi-Carbon-Newsletter-2-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2-100x100.jpg"},"shop_catalog":{"file":"OVV-AMi-Carbon-Newsletter-2-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2-300x300.jpg"},"shop_single":{"file":"OVV-AMi-Carbon-Newsletter-2-600x400.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2-600x400.jpg"},"shop_thumbnail":{"file":"OVV-AMi-Carbon-Newsletter-2-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2-100x100.jpg"},"full":{"file":"OVV-AMi-Carbon-Newsletter-2.jpg?fit=1400%2C934&ssl=1","width":1400,"height":934,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg?fit=1400%2C934&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.larouelibre.fr\/blog\/wp-content\/uploads\/2019\/01\/OVV-AMi-Carbon-Newsletter-2.jpg","_links":{"self":[{"href":"https:\/\/www.larouelibre.fr\/blog\/wp-json\/wp\/v2\/media\/20358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.larouelibre.fr\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.larouelibre.fr\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.larouelibre.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.larouelibre.fr\/blog\/wp-json\/wp\/v2\/comments?post=20358"}]}}